{"id":1,"count":1,"description":"Din bloggkategori","link":"https:\/\/oneclicktv.net\/officiella-sv\/kategori\/blogg\/","name":"Blogg","slug":"blogg","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/oneclicktv.net\/officiella-sv\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oneclicktv.net\/officiella-sv\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/oneclicktv.net\/officiella-sv\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/oneclicktv.net\/officiella-sv\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}