{"id":61,"count":1,"description":"","link":"https:\/\/oneclicktv.net\/fr-officiel\/categorie\/iptv-postsiptv-tips\/","name":"IPTV Posts|IPTV Tips","slug":"iptv-postsiptv-tips","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/oneclicktv.net\/fr-officiel\/wp-json\/wp\/v2\/categories\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oneclicktv.net\/fr-officiel\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/oneclicktv.net\/fr-officiel\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/oneclicktv.net\/fr-officiel\/wp-json\/wp\/v2\/posts?categories=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}